{"id":39,"count":1,"description":"","link":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/","name":"BULL TERRIER","slug":"bull-terrier","taxonomy":"category","parent":83,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BULL TERRIER Archivi - Travelling Dog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BULL TERRIER Archivi - Travelling Dog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/\" \/>\n<meta property=\"og:site_name\" content=\"Travelling Dog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/\",\"url\":\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/\",\"name\":\"BULL TERRIER Archivi - Travelling Dog\",\"isPartOf\":{\"@id\":\"https:\/\/www.travellingdogkennel.com\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.travellingdogkennel.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RAZZA CANE\",\"item\":\"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BULL TERRIER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.travellingdogkennel.com\/it\/#website\",\"url\":\"https:\/\/www.travellingdogkennel.com\/it\/\",\"name\":\"Travelling Dog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.travellingdogkennel.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BULL TERRIER Archivi - Travelling Dog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/","og_locale":"it_IT","og_type":"article","og_title":"BULL TERRIER Archivi - Travelling Dog","og_url":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/","og_site_name":"Travelling Dog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/","url":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/","name":"BULL TERRIER Archivi - Travelling Dog","isPartOf":{"@id":"https:\/\/www.travellingdogkennel.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/bull-terrier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.travellingdogkennel.com\/it\/"},{"@type":"ListItem","position":2,"name":"RAZZA CANE","item":"https:\/\/www.travellingdogkennel.com\/it\/category\/razza-cane\/"},{"@type":"ListItem","position":3,"name":"BULL TERRIER"}]},{"@type":"WebSite","@id":"https:\/\/www.travellingdogkennel.com\/it\/#website","url":"https:\/\/www.travellingdogkennel.com\/it\/","name":"Travelling Dog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.travellingdogkennel.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.travellingdogkennel.com\/it\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.travellingdogkennel.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.travellingdogkennel.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.travellingdogkennel.com\/it\/wp-json\/wp\/v2\/categories\/83"}],"wp:post_type":[{"href":"https:\/\/www.travellingdogkennel.com\/it\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}